{"id":890,"date":"2010-03-18T18:54:27","date_gmt":"2010-03-18T17:54:27","guid":{"rendered":"http:\/\/pl.doda-music.com\/?p=890"},"modified":"2010-03-18T18:54:27","modified_gmt":"2010-03-18T17:54:27","slug":"doda-wygrala-proces","status":"publish","type":"post","link":"https:\/\/pl.doda-music.com\/index.php\/2010\/03\/doda-wygrala-proces\/","title":{"rendered":"Doda wygra\u0142a proces!"},"content":{"rendered":"<p>Doda wygra\u0142a proces z Grup\u0105 Operacyjn\u0105. Lider zespo\u0142u ma przeprosi\u0107 Artystk\u0119 na portalu Onet.pl i na stronie internetowej zespo\u0142u. B\u0119dzie te\u017c musia\u0142 usun\u0105\u0107 ze swojej strony link do piosenki obra\u017caj\u0105cej Dod\u0119. Wi\u0119cej na stronie <a href=\"http:\/\/www.tvn24.pl\/-1,1648342,0,1,doda-to-nie-blachara--naleza-sie-jej-przeprosiny,wiadomosc.html\" target=\"_blank\">TVN24<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doda wygra\u0142a proces z Grup\u0105 Operacyjn\u0105. Lider zespo\u0142u ma przeprosi\u0107 Artystk\u0119 na portalu Onet.pl i na stronie internetowej zespo\u0142u. B\u0119dzie te\u017c musia\u0142 usun\u0105\u0107 ze swojej strony link do piosenki obra\u017caj\u0105cej Dod\u0119. Wi\u0119cej na stronie TVN24.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"_links":{"self":[{"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/posts\/890"}],"collection":[{"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":1,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":891,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/posts\/890\/revisions\/891"}],"wp:attachment":[{"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pl.doda-music.com\/index.php\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}